{"id":909,"count":5,"description":"","link":"https:\/\/prowrestling.net\/site\/tag\/wwe-roster-split\/","name":"wwe roster split","slug":"wwe-roster-split","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>wwe roster split Archives - Pro Wrestling Dot Net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prowrestling.net\/site\/tag\/wwe-roster-split\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"wwe roster split Archives - Pro Wrestling Dot Net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prowrestling.net\/site\/tag\/wwe-roster-split\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Wrestling Dot Net\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/tag\\\/wwe-roster-split\\\/\",\"url\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/tag\\\/wwe-roster-split\\\/\",\"name\":\"wwe roster split Archives - Pro Wrestling Dot Net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/tag\\\/wwe-roster-split\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/tag\\\/wwe-roster-split\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"wwe roster split\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/\",\"name\":\"Pro Wrestling Dot Net\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"wwe roster split Archives - Pro Wrestling Dot Net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prowrestling.net\/site\/tag\/wwe-roster-split\/","og_locale":"en_US","og_type":"article","og_title":"wwe roster split Archives - Pro Wrestling Dot Net","og_url":"https:\/\/prowrestling.net\/site\/tag\/wwe-roster-split\/","og_site_name":"Pro Wrestling Dot Net","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/prowrestling.net\/site\/tag\/wwe-roster-split\/","url":"https:\/\/prowrestling.net\/site\/tag\/wwe-roster-split\/","name":"wwe roster split Archives - Pro Wrestling Dot Net","isPartOf":{"@id":"https:\/\/prowrestling.net\/site\/#website"},"breadcrumb":{"@id":"https:\/\/prowrestling.net\/site\/tag\/wwe-roster-split\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/prowrestling.net\/site\/tag\/wwe-roster-split\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prowrestling.net\/site\/"},{"@type":"ListItem","position":2,"name":"wwe roster split"}]},{"@type":"WebSite","@id":"https:\/\/prowrestling.net\/site\/#website","url":"https:\/\/prowrestling.net\/site\/","name":"Pro Wrestling Dot Net","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prowrestling.net\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/tags\/909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/posts?tags=909"},{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/podcast?tags=909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}