{"id":83412,"date":"2020-12-11T20:50:03","date_gmt":"2020-12-12T02:50:03","guid":{"rendered":"https:\/\/prowrestling.net\/site\/?p=83412"},"modified":"2020-12-11T12:53:55","modified_gmt":"2020-12-11T18:53:55","slug":"wwe-friday-night-smackdown-poll-grade-the-december-11-edition","status":"publish","type":"post","link":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/","title":{"rendered":"WWE Friday Night Smackdown Poll: Grade the December 11 edition"},"content":{"rendered":"<div id=\"prowr-359839034\" class=\"prowr-apple-podcast-button-link prowr-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/pro-wrestling-boom-podcast\/id1365989370\" aria-label=\"SUBSCRIBE IN APPLE PODCASTS\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/advanced_ads\/2019\/07\/Logo2019_ApplePodcasts_320wide.png?fit=320%2C78&#038;ssl=1\" alt=\"SUBSCRIBE IN APPLE PODCASTS\"  srcset=\"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/advanced_ads\/2019\/07\/Logo2019_ApplePodcasts_320wide.png?w=320&ssl=1 320w, https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/advanced_ads\/2019\/07\/Logo2019_ApplePodcasts_320wide.png?resize=300%2C73&ssl=1 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" width=\"320\" height=\"78\"   \/><\/a><\/div><form action=\"https:\/\/poll.pollcode.com\/98511369\" method=\"post\">\n<div style=\"background-color: #eeeeee; padding: 2px; width: 175px; font-family: Arial; font-size: small; color: #000000;\">\n<div style=\"padding: 2px 0px 4px 2px;\"><strong>WWE Friday Night Smackdown Poll: Grade the December 11 edition<\/strong><\/div>\n<p><input id=\"answer985113691\" style=\"float: left;\" name=\"answer\" type=\"radio\" value=\"1\" \/><label style=\"float: left; width: 150px;\" for=\"answer985113691\">A &#8211; Great Show<\/label><\/p>\n<div style=\"clear: both; height: 2px;\"><\/div>\n<p><input id=\"answer985113692\" style=\"float: left;\" name=\"answer\" type=\"radio\" value=\"2\" \/><label style=\"float: left; width: 150px;\" for=\"answer985113692\">B &#8211; Good Show<\/label><\/p>\n<div style=\"clear: both; height: 2px;\"><\/div>\n<p><input id=\"answer985113693\" style=\"float: left;\" name=\"answer\" type=\"radio\" value=\"3\" \/><label style=\"float: left; width: 150px;\" for=\"answer985113693\">C &#8211; Average Show<\/label><\/p>\n<div style=\"clear: both; height: 2px;\"><\/div>\n<p><input id=\"answer985113694\" style=\"float: left;\" name=\"answer\" type=\"radio\" value=\"4\" \/><label style=\"float: left; width: 150px;\" for=\"answer985113694\">D &#8211; Disappointing Show<\/label><\/p>\n<div style=\"clear: both; height: 2px;\"><\/div>\n<p><input id=\"answer985113695\" style=\"float: left;\" name=\"answer\" type=\"radio\" value=\"5\" \/><label style=\"float: left; width: 150px;\" for=\"answer985113695\">F &#8211; Awful Show<\/label><\/p>\n<div style=\"clear: both; height: 2px;\"><\/div>\n<div style=\"padding: 3px;\" align=\"center\"><input type=\"submit\" value=\" Vote \" \/>\u00a0<input name=\"view\" type=\"submit\" value=\" View \" \/><\/div>\n<div style=\"font-size: 10px;\" align=\"right\">pollcode.com <a href=\"https:\/\/pollcode.com\/\">free polls<\/a><\/div>\n<\/div>\n<\/form>\n<div id=\"prowr-1381346171\" class=\"prowr-after-content prowr-entity-placement\"><a class=\"spreaker-player\" href=\"https:\/\/www.spreaker.com\/show\/pwboom\" data-resource=\"show_id=3275525\" data-theme=\"light\" data-playlist=\"show\" data-width=\"100%\" data-height=\"340px\">Listen to \"Pro Wrestling Boom Podcast\" on Spreaker.<\/a><script async src=\"https:\/\/widget.spreaker.com\/widgets.js\"><\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>WWE Friday Night Smackdown Poll:&#8230;<\/p>\n","protected":false},"author":5,"featured_media":62533,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[50,28],"tags":[128,101,3042,31,272],"class_list":["post-83412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mustreadarticles","category-reader_polls","tag-pro-wrestling","tag-wwe","tag-wwe-friday-night-smackdown","tag-wwe-smackdown","tag-wwe-tlc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WWE Friday Night Smackdown Poll: Grade the December 11 edition - Pro Wrestling Dot Net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WWE Friday Night Smackdown Poll: Grade the December 11 edition - Pro Wrestling Dot Net\" \/>\n<meta property=\"og:description\" content=\"WWE Friday Night Smackdown Poll:...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Wrestling Dot Net\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-12T02:50:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2019\/10\/newsdwhite.png?fit=275%2C183&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jason Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jason Powell\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/\"},\"author\":{\"name\":\"Jason Powell\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#\\\/schema\\\/person\\\/ff3b4e448549ff94ff694c757fddb15a\"},\"headline\":\"WWE Friday Night Smackdown Poll: Grade the December 11 edition\",\"datePublished\":\"2020-12-12T02:50:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/\"},\"wordCount\":42,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prowrestling.net\\\/site\\\/wp-content\\\/uploads\\\/post\\\/2019\\\/10\\\/newsdwhite.png?fit=275%2C183&ssl=1\",\"keywords\":[\"pro wrestling\",\"wwe\",\"wwe friday night smackdown\",\"wwe smackdown\",\"wwe tlc\"],\"articleSection\":[\"MUST-READ LIST\",\"READER POLLS\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/\",\"url\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/\",\"name\":\"WWE Friday Night Smackdown Poll: Grade the December 11 edition - Pro Wrestling Dot Net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prowrestling.net\\\/site\\\/wp-content\\\/uploads\\\/post\\\/2019\\\/10\\\/newsdwhite.png?fit=275%2C183&ssl=1\",\"datePublished\":\"2020-12-12T02:50:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#\\\/schema\\\/person\\\/ff3b4e448549ff94ff694c757fddb15a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prowrestling.net\\\/site\\\/wp-content\\\/uploads\\\/post\\\/2019\\\/10\\\/newsdwhite.png?fit=275%2C183&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prowrestling.net\\\/site\\\/wp-content\\\/uploads\\\/post\\\/2019\\\/10\\\/newsdwhite.png?fit=275%2C183&ssl=1\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2020\\\/12\\\/11\\\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WWE Friday Night Smackdown Poll: Grade the December 11 edition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/\",\"name\":\"Pro Wrestling Dot Net\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#\\\/schema\\\/person\\\/ff3b4e448549ff94ff694c757fddb15a\",\"name\":\"Jason Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g\",\"caption\":\"Jason Powell\"},\"sameAs\":[\"http:\\\/\\\/www.prowrestling.net\"],\"url\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/author\\\/jasonpowell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WWE Friday Night Smackdown Poll: Grade the December 11 edition - Pro Wrestling Dot Net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/","og_locale":"en_US","og_type":"article","og_title":"WWE Friday Night Smackdown Poll: Grade the December 11 edition - Pro Wrestling Dot Net","og_description":"WWE Friday Night Smackdown Poll:...","og_url":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/","og_site_name":"Pro Wrestling Dot Net","article_published_time":"2020-12-12T02:50:03+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/i2.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2019\/10\/newsdwhite.png?fit=275%2C183&ssl=1","type":"image\/png"}],"author":"Jason Powell","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jason Powell"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/#article","isPartOf":{"@id":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/"},"author":{"name":"Jason Powell","@id":"https:\/\/prowrestling.net\/site\/#\/schema\/person\/ff3b4e448549ff94ff694c757fddb15a"},"headline":"WWE Friday Night Smackdown Poll: Grade the December 11 edition","datePublished":"2020-12-12T02:50:03+00:00","mainEntityOfPage":{"@id":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/"},"wordCount":42,"commentCount":0,"image":{"@id":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2019\/10\/newsdwhite.png?fit=275%2C183&ssl=1","keywords":["pro wrestling","wwe","wwe friday night smackdown","wwe smackdown","wwe tlc"],"articleSection":["MUST-READ LIST","READER POLLS"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/","url":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/","name":"WWE Friday Night Smackdown Poll: Grade the December 11 edition - Pro Wrestling Dot Net","isPartOf":{"@id":"https:\/\/prowrestling.net\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/#primaryimage"},"image":{"@id":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2019\/10\/newsdwhite.png?fit=275%2C183&ssl=1","datePublished":"2020-12-12T02:50:03+00:00","author":{"@id":"https:\/\/prowrestling.net\/site\/#\/schema\/person\/ff3b4e448549ff94ff694c757fddb15a"},"breadcrumb":{"@id":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/#primaryimage","url":"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2019\/10\/newsdwhite.png?fit=275%2C183&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2019\/10\/newsdwhite.png?fit=275%2C183&ssl=1","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/prowrestling.net\/site\/2020\/12\/11\/wwe-friday-night-smackdown-poll-grade-the-december-11-edition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prowrestling.net\/site\/"},{"@type":"ListItem","position":2,"name":"WWE Friday Night Smackdown Poll: Grade the December 11 edition"}]},{"@type":"WebSite","@id":"https:\/\/prowrestling.net\/site\/#website","url":"https:\/\/prowrestling.net\/site\/","name":"Pro Wrestling Dot Net","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prowrestling.net\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/prowrestling.net\/site\/#\/schema\/person\/ff3b4e448549ff94ff694c757fddb15a","name":"Jason Powell","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g","caption":"Jason Powell"},"sameAs":["http:\/\/www.prowrestling.net"],"url":"https:\/\/prowrestling.net\/site\/author\/jasonpowell\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2019\/10\/newsdwhite.png?fit=275%2C183&ssl=1","_links":{"self":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/posts\/83412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/comments?post=83412"}],"version-history":[{"count":1,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/posts\/83412\/revisions"}],"predecessor-version":[{"id":83413,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/posts\/83412\/revisions\/83413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/media\/62533"}],"wp:attachment":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/media?parent=83412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/categories?post=83412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/tags?post=83412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}