{"id":125717,"date":"2023-02-19T00:10:21","date_gmt":"2023-02-19T06:10:21","guid":{"rendered":"https:\/\/prowrestling.net\/site\/?p=125717"},"modified":"2023-02-19T00:10:21","modified_gmt":"2023-02-19T06:10:21","slug":"02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho","status":"publish","type":"post","link":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/","title":{"rendered":"02\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor"},"content":{"rendered":"<div id=\"prowr-1264446084\" class=\"prowr-apple-podcast-button-link prowr-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/pro-wrestling-boom-podcast\/id1365989370\" aria-label=\"SUBSCRIBE IN APPLE PODCASTS\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/advanced_ads\/2019\/07\/Logo2019_ApplePodcasts_320wide.png?fit=320%2C78&#038;ssl=1\" alt=\"SUBSCRIBE IN APPLE PODCASTS\"  srcset=\"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/advanced_ads\/2019\/07\/Logo2019_ApplePodcasts_320wide.png?w=320&ssl=1 320w, https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/advanced_ads\/2019\/07\/Logo2019_ApplePodcasts_320wide.png?resize=300%2C73&ssl=1 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" width=\"320\" height=\"78\"   \/><\/a><\/div><p><b>By Jason Powell<\/b>\u00a0(<a href=\"https:\/\/twitter.com\/prowrestlingnet\" target=\"_blank\" rel=\"noopener noreferrer\">@prowrestlingnet<\/a>), <strong>Jake Barnett<\/strong>\u00a0(<a href=\"https:\/\/twitter.com\/barnettjake\">@barnettjake<\/a>), and <b>Will Pruett<\/b><span style=\"font-weight: 400;\">\u00a0(<\/span><a href=\"https:\/\/twitter.com\/itswilltime\"><span style=\"font-weight: 400;\">@itswilltime<\/span><\/a><span style=\"font-weight: 400;\">)<\/span><\/p>\n<p>Jason Powell, Jake Barnett, and Will Pruett review the WWE Elimination Chamber premium live event: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor, and more (65:36)&#8230;<\/p>\n<p>Click here for the <a href=\"http:\/\/www.prowrestling.net\/mobileaudio\/uploads\/wp-media\/2023\/02\/20230218wwechamber.mp3\">WWE Elimination Chamber 2023 audio review.<\/a><\/p>\n<p>If you are not a subscriber, click here\u00a0to become a <a href=\"http:\/\/www.prowrestling.net\/amember\/signup.php\">Dot Net Member.<\/a><\/p>\n<p class=\"p1\">\n<div id=\"prowr-2689172272\" class=\"prowr-after-content prowr-entity-placement\"><a class=\"spreaker-player\" href=\"https:\/\/www.spreaker.com\/show\/pwboom\" data-resource=\"show_id=3275525\" data-theme=\"light\" data-playlist=\"show\" data-width=\"100%\" data-height=\"340px\">Listen to \"Pro Wrestling Boom Podcast\" on Spreaker.<\/a><script async src=\"https:\/\/widget.spreaker.com\/widgets.js\"><\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>By Jason Powell\u00a0(@prowrestlingnet), Jake Barnett\u00a0(@barnettjake),&#8230;<\/p>\n","protected":false},"author":5,"featured_media":108208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[81,50,2,30],"tags":[126,1408,1354,68,107,2932,398,2870,3531,355,1324,47,1103,1987,376,109,1147,3107,187,1403,174,4468,1810,54,38,149,4260,3859,4358,101,1420],"class_list":["post-125717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-memberaudio","category-mustreadarticles","category-newsticker","category-podcasts","tag-asuka","tag-austin-theory","tag-beth-phoenix","tag-bobby-lashley","tag-brock-lesnar","tag-bronson-reed","tag-carmella","tag-damian-priest","tag-dominik-mysterio","tag-edge","tag-elimination-chamber","tag-finn-balor","tag-jey-uso","tag-jimmy-uso","tag-johnny-gargano","tag-kevin-owens","tag-liv-morgan","tag-montez-ford","tag-natalya","tag-nikki-cross","tag-paul-heyman","tag-raquel-rodriguez","tag-rhea-ripley","tag-roman-reigns","tag-sami-zayn","tag-seth-rollins","tag-solo-sikoa","tag-the-bloodline","tag-wm39","tag-wwe","tag-wwe-elimination-chamber"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>02\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor - Pro Wrestling Dot Net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"02\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor - Pro Wrestling Dot Net\" \/>\n<meta property=\"og:description\" content=\"By Jason Powell\u00a0(@prowrestlingnet), Jake Barnett\u00a0(@barnettjake),...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Wrestling Dot Net\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-19T06:10:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prowrestling.net\/site\/wp-content\/uploads\/post\/2022\/03\/DotNet2022_PodcastRectangle_Members.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jason Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jason Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/\"},\"author\":{\"name\":\"Jason Powell\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#\\\/schema\\\/person\\\/ff3b4e448549ff94ff694c757fddb15a\"},\"headline\":\"02\\\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor\",\"datePublished\":\"2023-02-19T06:10:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/\"},\"wordCount\":116,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prowrestling.net\\\/site\\\/wp-content\\\/uploads\\\/post\\\/2022\\\/03\\\/DotNet2022_PodcastRectangle_Members.png?fit=1800%2C1200&ssl=1\",\"keywords\":[\"asuka\",\"austin theory\",\"beth phoenix\",\"bobby lashley\",\"brock lesnar\",\"bronson reed\",\"carmella\",\"damian priest\",\"dominik mysterio\",\"edge\",\"elimination chamber\",\"finn balor\",\"jey uso\",\"jimmy uso\",\"johnny gargano\",\"kevin owens\",\"liv morgan\",\"montez ford\",\"natalya\",\"nikki cross\",\"paul heyman\",\"raquel rodriguez\",\"rhea ripley\",\"roman reigns\",\"sami zayn\",\"seth rollins\",\"solo sikoa\",\"the bloodline\",\"wm39\",\"wwe\",\"wwe elimination chamber\"],\"articleSection\":[\"Member Exclusive Podcasts\",\"MUST-READ LIST\",\"NEWS TICKER\",\"PODCASTS\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/\",\"url\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/\",\"name\":\"02\\\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor - Pro Wrestling Dot Net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prowrestling.net\\\/site\\\/wp-content\\\/uploads\\\/post\\\/2022\\\/03\\\/DotNet2022_PodcastRectangle_Members.png?fit=1800%2C1200&ssl=1\",\"datePublished\":\"2023-02-19T06:10:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#\\\/schema\\\/person\\\/ff3b4e448549ff94ff694c757fddb15a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prowrestling.net\\\/site\\\/wp-content\\\/uploads\\\/post\\\/2022\\\/03\\\/DotNet2022_PodcastRectangle_Members.png?fit=1800%2C1200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prowrestling.net\\\/site\\\/wp-content\\\/uploads\\\/post\\\/2022\\\/03\\\/DotNet2022_PodcastRectangle_Members.png?fit=1800%2C1200&ssl=1\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/2023\\\/02\\\/19\\\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"02\\\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/\",\"name\":\"Pro Wrestling Dot Net\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/#\\\/schema\\\/person\\\/ff3b4e448549ff94ff694c757fddb15a\",\"name\":\"Jason Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g\",\"caption\":\"Jason Powell\"},\"sameAs\":[\"http:\\\/\\\/www.prowrestling.net\"],\"url\":\"https:\\\/\\\/prowrestling.net\\\/site\\\/author\\\/jasonpowell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"02\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor - Pro Wrestling Dot Net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/","og_locale":"en_US","og_type":"article","og_title":"02\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor - Pro Wrestling Dot Net","og_description":"By Jason Powell\u00a0(@prowrestlingnet), Jake Barnett\u00a0(@barnettjake),...","og_url":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/","og_site_name":"Pro Wrestling Dot Net","article_published_time":"2023-02-19T06:10:21+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/prowrestling.net\/site\/wp-content\/uploads\/post\/2022\/03\/DotNet2022_PodcastRectangle_Members.png","type":"image\/png"}],"author":"Jason Powell","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jason Powell","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/#article","isPartOf":{"@id":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/"},"author":{"name":"Jason Powell","@id":"https:\/\/prowrestling.net\/site\/#\/schema\/person\/ff3b4e448549ff94ff694c757fddb15a"},"headline":"02\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor","datePublished":"2023-02-19T06:10:21+00:00","mainEntityOfPage":{"@id":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/"},"wordCount":116,"commentCount":0,"image":{"@id":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2022\/03\/DotNet2022_PodcastRectangle_Members.png?fit=1800%2C1200&ssl=1","keywords":["asuka","austin theory","beth phoenix","bobby lashley","brock lesnar","bronson reed","carmella","damian priest","dominik mysterio","edge","elimination chamber","finn balor","jey uso","jimmy uso","johnny gargano","kevin owens","liv morgan","montez ford","natalya","nikki cross","paul heyman","raquel rodriguez","rhea ripley","roman reigns","sami zayn","seth rollins","solo sikoa","the bloodline","wm39","wwe","wwe elimination chamber"],"articleSection":["Member Exclusive Podcasts","MUST-READ LIST","NEWS TICKER","PODCASTS"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/","url":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/","name":"02\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor - Pro Wrestling Dot Net","isPartOf":{"@id":"https:\/\/prowrestling.net\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/#primaryimage"},"image":{"@id":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2022\/03\/DotNet2022_PodcastRectangle_Members.png?fit=1800%2C1200&ssl=1","datePublished":"2023-02-19T06:10:21+00:00","author":{"@id":"https:\/\/prowrestling.net\/site\/#\/schema\/person\/ff3b4e448549ff94ff694c757fddb15a"},"breadcrumb":{"@id":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/#primaryimage","url":"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2022\/03\/DotNet2022_PodcastRectangle_Members.png?fit=1800%2C1200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2022\/03\/DotNet2022_PodcastRectangle_Members.png?fit=1800%2C1200&ssl=1","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/prowrestling.net\/site\/2023\/02\/19\/02-18-wwe-elimination-chamber-audio-review-roman-reigns-vs-sami-zayn-for-the-undisputed-wwe-universal-championship-brock-lesnar-vs-bobby-lashley-two-elimination-chamber-matches-edge-and-beth-pho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prowrestling.net\/site\/"},{"@type":"ListItem","position":2,"name":"02\/18 WWE Elimination Chamber audio review: Roman Reigns vs. Sami Zayn for the Undisputed WWE Universal Championship, Brock Lesnar vs. Bobby Lashley, two Elimination Chamber matches, Edge and Beth Phoenix vs. Rhea Ripley and Finn Balor"}]},{"@type":"WebSite","@id":"https:\/\/prowrestling.net\/site\/#website","url":"https:\/\/prowrestling.net\/site\/","name":"Pro Wrestling Dot Net","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prowrestling.net\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/prowrestling.net\/site\/#\/schema\/person\/ff3b4e448549ff94ff694c757fddb15a","name":"Jason Powell","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55404fadaa69294c803ac04b96567c09dd489324349001f369a73654f363280d?s=96&d=mm&r=g","caption":"Jason Powell"},"sameAs":["http:\/\/www.prowrestling.net"],"url":"https:\/\/prowrestling.net\/site\/author\/jasonpowell\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prowrestling.net\/site\/wp-content\/uploads\/post\/2022\/03\/DotNet2022_PodcastRectangle_Members.png?fit=1800%2C1200&ssl=1","_links":{"self":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/posts\/125717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/comments?post=125717"}],"version-history":[{"count":2,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/posts\/125717\/revisions"}],"predecessor-version":[{"id":125772,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/posts\/125717\/revisions\/125772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/media\/108208"}],"wp:attachment":[{"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/media?parent=125717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/categories?post=125717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prowrestling.net\/site\/wp-json\/wp\/v2\/tags?post=125717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}